{"id":20893,"date":"2018-07-16T11:46:46","date_gmt":"2018-07-16T14:46:46","guid":{"rendered":"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/?page_id=20893"},"modified":"2026-08-27T11:24:35","modified_gmt":"2026-08-27T14:24:35","slug":"almoxarifado-central","status":"publish","type":"page","link":"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/almoxarifado-central","title":{"rendered":"Almoxarifado Central"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"20893\" class=\"elementor elementor-20893\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50cf7f62 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50cf7f62\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76f40672\" data-id=\"76f40672\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7831143a elementor-widget elementor-widget-text-editor\" data-id=\"7831143a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-family: verdana, geneva, sans-serif\">O <strong>Almoxarifado Central<\/strong> tem como objetivo, disponibilizar o fornecimento de materiais de consumo necess\u00e1rios para os andamentos das atividades letivas e administrativas na <strong>Universidade Federal de Santa Maria (UFSM)<\/strong>, bem como realizar as recep\u00e7\u00f5es, confer\u00eancias e distribui\u00e7\u00f5es dos produtos de consumo, adquiridos pelos demais departamentos e sub-unidades. Opera em um espa\u00e7o com 2,5 mil metros quadrados para receber, armazenar e distribuir os materiais de consumo e estoques da UFSM. O pr\u00e9dio de 1,5 mil metros quadrados de \u00e1rea constru\u00edda, conta com um moderno sistema de armazenamento, que inclui um elevador de cargas com capacidade de uma tonelada. Com a instala\u00e7\u00e3o de tr\u00eas pavimentos met\u00e1licos (mezaninos) dentro da \u00e1rea do edif\u00edcio, foi poss\u00edvel disponibilizar mais mil metros quadrados para o armazenamento de produtos, al\u00e9m dos 1,5 mil metros quadrados de \u00e1rea total de que o pr\u00e9dio j\u00e1 dispunha.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-605f745 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"605f745\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e3ceac\" data-id=\"3e3ceac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6a8d5f elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"a6a8d5f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f75a8e7\" data-id=\"f75a8e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44695f1 elementor-view-framed elementor-widget__width-initial elementor-shape-circle elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"44695f1\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/perguntas-e-respostas-almoxarifado-central\" target=\"_blank\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-question\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/perguntas-e-respostas-almoxarifado-central\" target=\"_blank\" >\n\t\t\t\t\t\t\tPerguntas Frequentes\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-061df14 elementor-view-framed elementor-widget__width-initial elementor-shape-circle elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"061df14\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/produtos-em-estoque\" target=\"_blank\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-warehouse\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/produtos-em-estoque\" target=\"_blank\" >\n\t\t\t\t\t\t\tConsulta estoque\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd5cab0 elementor-view-framed elementor-widget__width-initial elementor-shape-circle elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"dd5cab0\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.ufsm.br\/app\/uploads\/sites\/352\/2024\/03\/Manual_almoxarifado_central.pdf\" target=\"_blank\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-download\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.ufsm.br\/app\/uploads\/sites\/352\/2024\/03\/Manual_almoxarifado_central.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\tManual do Almoxarifado\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9798bf7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9798bf7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-93fdd46\" data-id=\"93fdd46\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>O Almoxarifado Central tem como objetivo, disponibilizar o fornecimento de materiais de consumo necess\u00e1rios para os andamentos das atividades letivas e administrativas na Universidade Federal de Santa Maria (UFSM), bem como realizar as recep\u00e7\u00f5es, confer\u00eancias e distribui\u00e7\u00f5es dos produtos de consumo, adquiridos pelos demais departamentos e sub-unidades. Opera em um espa\u00e7o com 2,5 mil metros [&hellip;]<\/p>\n","protected":false},"author":115,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-20893","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/wp-json\/wp\/v2\/pages\/20893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/wp-json\/wp\/v2\/users\/115"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/wp-json\/wp\/v2\/comments?post=20893"}],"version-history":[{"count":0,"href":"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/wp-json\/wp\/v2\/pages\/20893\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/wp-json\/wp\/v2\/media?parent=20893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/wp-json\/wp\/v2\/categories?post=20893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ufsm.br\/orgaos-executivos\/demapa\/wp-json\/wp\/v2\/tags?post=20893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}