{"id":3959,"date":"2016-11-04T17:43:22","date_gmt":"2016-11-04T19:43:22","guid":{"rendered":"https:\/\/www.ufsm.br\/orgaos-suplementares\/radio\/2016\/11\/04\/aquarela2016-11-06\/"},"modified":"2016-11-04T17:43:22","modified_gmt":"2016-11-04T19:43:22","slug":"aquarela2016-11-06","status":"publish","type":"post","link":"https:\/\/www.ufsm.br\/orgaos-suplementares\/radio\/2016\/11\/04\/aquarela2016-11-06","title":{"rendered":"Aquarela pelos 800 AM neste domingo, 06\/11"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" alignleft size-full wp-image-3958\" style=\"margin-right: 10px; float: left;\" title=\"Aquarela\" src=\"https:\/\/www.ufsm.br\/orgaos-suplementares\/radio\/wp-content\/uploads\/sites\/411\/2016\/11\/aquarela.jpg\" alt=\"Aquarela\" width=\"250\" height=\"200\" \/>A m&uacute;sica do Brasil &eacute; reconhecida mundialmente pela sua diversidade e, em muitas cria&ccedil;&otilde;es, sua universalidade. A m&uacute;sica instrumental brasileira em toda sua plenitude est&aacute; no <strong>Aquarela<\/strong>, espa&ccedil;o exclusivo para receber instrumentos e orquestras de todo o pa&iacute;s nos <strong>800 AM<\/strong>.<\/p>\n<p>A cada semana, o programa re&uacute;ne execu&ccedil;&otilde;es de jovens nomes da m&uacute;sica instrumental brasileira, nunca esquecendo dos grandes mestres do cancioneiro tocado deste pa&iacute;s continente.<\/p>\n<p>O <strong> Aquarela<\/strong> vai ao ar todo domingo pela <strong>R&aacute;dio Universidade<\/strong>, na faixa das 12h00 &agrave;s 13h00. A pesquisa, produ&ccedil;&atilde;o, apresenta&ccedil;&atilde;o e edi&ccedil;&atilde;o &eacute; de Milton Oliveira. O programa pode ser ouvido pelos <strong> 800 AM<\/strong> e aqui no site via web.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A m&uacute;sica do Brasil &eacute; reconhecida mundialmente pela sua diversidade e, em muitas cria&ccedil;&otilde;es, sua universalidade. A m&uacute;sica instrumental brasileira em toda sua plenitude est&aacute; no Aquarela, espa&ccedil;o exclusivo para receber instrumentos e orquestras de todo o pa&iacute;s nos 800 AM. A cada semana, o programa re&uacute;ne execu&ccedil;&otilde;es de jovens nomes da m&uacute;sica instrumental brasileira, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-3959","post","type-post","status-publish","format-standard","hentry","category-geral"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ufsm.br\/orgaos-suplementares\/radio\/wp-json\/wp\/v2\/posts\/3959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ufsm.br\/orgaos-suplementares\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ufsm.br\/orgaos-suplementares\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ufsm.br\/orgaos-suplementares\/radio\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ufsm.br\/orgaos-suplementares\/radio\/wp-json\/wp\/v2\/comments?post=3959"}],"version-history":[{"count":0,"href":"https:\/\/www.ufsm.br\/orgaos-suplementares\/radio\/wp-json\/wp\/v2\/posts\/3959\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ufsm.br\/orgaos-suplementares\/radio\/wp-json\/wp\/v2\/media?parent=3959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ufsm.br\/orgaos-suplementares\/radio\/wp-json\/wp\/v2\/categories?post=3959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ufsm.br\/orgaos-suplementares\/radio\/wp-json\/wp\/v2\/tags?post=3959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}